{"id":45534,"count":1,"description":"","link":"https:\/\/www.fami-geki.com\/douga\/director\/%e3%83%9e%e3%83%83%e3%83%88%e3%83%bb%e3%83%99%e3%83%86%e3%82%a3%e3%83%8d%e3%83%83%e3%83%aa%ef%bc%9d%e3%82%aa%e3%83%ab%e3%83%94%e3%83%b3\/","name":"\u30de\u30c3\u30c8\u30fb\u30d9\u30c6\u30a3\u30cd\u30c3\u30ea\uff1d\u30aa\u30eb\u30d4\u30f3","slug":"%e3%83%9e%e3%83%83%e3%83%88%e3%83%bb%e3%83%99%e3%83%86%e3%82%a3%e3%83%8d%e3%83%83%e3%83%aa%ef%bc%9d%e3%82%aa%e3%83%ab%e3%83%94%e3%83%b3","taxonomy":"director","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fami-geki.com\/douga\/wp-json\/wp\/v2\/director\/45534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fami-geki.com\/douga\/wp-json\/wp\/v2\/director"}],"about":[{"href":"https:\/\/www.fami-geki.com\/douga\/wp-json\/wp\/v2\/taxonomies\/director"}],"wp:post_type":[{"href":"https:\/\/www.fami-geki.com\/douga\/wp-json\/wp\/v2\/posts?director=45534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}