{"id":35099,"count":1,"description":"","link":"https:\/\/www.fami-geki.com\/douga\/director\/%e3%82%ad%e3%83%a0%e3%83%bb%e3%83%87%e3%82%b9%e3%83%b3\/","name":"\u30ad\u30e0\u30fb\u30c7\u30b9\u30f3","slug":"%e3%82%ad%e3%83%a0%e3%83%bb%e3%83%87%e3%82%b9%e3%83%b3","taxonomy":"director","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fami-geki.com\/douga\/wp-json\/wp\/v2\/director\/35099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fami-geki.com\/douga\/wp-json\/wp\/v2\/director"}],"about":[{"href":"https:\/\/www.fami-geki.com\/douga\/wp-json\/wp\/v2\/taxonomies\/director"}],"wp:post_type":[{"href":"https:\/\/www.fami-geki.com\/douga\/wp-json\/wp\/v2\/posts?director=35099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}